{"id":2364,"date":"2023-12-19T10:34:12","date_gmt":"2023-12-19T10:34:12","guid":{"rendered":"https:\/\/allirajahsubaskaran.com\/la-industria-audiovisual-y-del-entretenimiento-hindu\/"},"modified":"2023-12-19T10:34:12","modified_gmt":"2023-12-19T10:34:12","slug":"la-industria-audiovisual-y-del-entretenimiento-hindu","status":"publish","type":"post","link":"https:\/\/allirajahsubaskaran.com\/es\/la-industria-audiovisual-y-del-entretenimiento-hindu\/","title":{"rendered":"La industria audiovisual y del entretenimiento hind\u00fa"},"content":{"rendered":"<p><a href=\"https:\/\/www.lycagroup.com\/our-team-bio\">Allirajah Subaskaran<\/a> es el fundador de Lyca Group, una organizaci\u00f3n con filiales que operan en distintos sectores, incluidos los medios de comunicaci\u00f3n y el entretenimiento. Como presidente de Lyca Productions, Allirajah Subashkaran ha supervisado la creaci\u00f3n de varios \u00e9xitos de taquilla con un presupuesto de m\u00e1s de 50 millones de libras, produciendo historias \u00e9picas en tamil, hindi, malayalam, kanada y telugu para su distribuci\u00f3n internacional.<\/p>\n<p>En este art\u00edculo se analiza la <a href=\"https:\/\/variety.com\/2023\/tv\/news\/india-media-entertainment-industry-growth-pwc-1235672802\/\">industria audiovisual y del entretenimiento hind\u00fa<\/a>, un mercado que, seg\u00fan las previsiones, experimentar\u00e1 un crecimiento significativo a lo largo de 2023 y a\u00f1os siguientes.<\/p>\n<p>Seg\u00fan un informe de PwC, el sector audiovisual y del entretenimiento hind\u00fa crecer\u00e1 un 9% de aqu\u00ed a 2027 y alcanzar\u00e1 un valor de 73.000 millones de d\u00f3lares. En t\u00e9rminos de porcentaje de crecimiento, el mercado streaming del pa\u00eds encabeza la lista, con un aumento de los ingresos del 25% en 2022.<\/p>\n<p>El informe Global Entertainment &amp; Media Outlook 2023-2027 de PwC sugiere que el mercado streaming de la India seguir\u00e1 creciendo a una tasa compuesta de crecimiento anual (TCAC) del 14%, produciendo unos ingresos de unos 3.500 millones de d\u00f3lares en 2027.<\/p>\n<p>Seg\u00fan un informe publicado por EY en la conferencia Frames celebrada en Mumbai en mayo de 2023, la industria audiovisual y del entretenimiento hind\u00fa creci\u00f3 un 20%, alcanzando los 26.000 millones de d\u00f3lares en 2022, lo que representa un aumento del 10% respecto a su valoraci\u00f3n previa a la pandemia de 2019. El informe recopil\u00f3 datos de cine, televisi\u00f3n, animaci\u00f3n y VFX, medios digitales, eventos en directo, medios fuera del hogar, radio, prensa, juegos en l\u00ednea y m\u00fasica. Predijo que, en general, el sector crecer\u00e1 un 12%, alcanzando un valor de 28.600 millones de d\u00f3lares en 2023.<\/p>\n<p>Aunque la televisi\u00f3n sigui\u00f3 siendo el mayor representante del sector audiovisual y del entretenimiento en la India en 2022, con una valoraci\u00f3n de aproximadamente 8.600 millones de d\u00f3lares, su valor se redujo en comparaci\u00f3n con los niveles de 2021, a pesar de que los ingresos publicitarios aumentaron un 2%, alcanzando niveles ligeramente inferiores a los de 2019. No obstante, el informe de EY suger\u00eda que el mercado televisivo hind\u00fa crecer\u00eda ligeramente a lo largo de 2023, hasta alcanzar una valoraci\u00f3n de 8.800 millones de d\u00f3lares.<\/p>\n<p>Los medios digitales fueron el segundo componente m\u00e1s importante del sector de medios y entretenimiento de la India, valorado en 6.900 millones de d\u00f3lares en 2022 seg\u00fan el informe de EY, y se prev\u00e9 que crezca hasta los 8.200 millones de d\u00f3lares en 2023. El informe se\u00f1alaba que la penetraci\u00f3n de Internet hab\u00eda aumentado un 4%, alcanzando los 866 millones de suscripciones en diciembre de 2022, lo que convierte a la India en la segunda mayor base de suscriptores de banda ancha del mundo despu\u00e9s de China.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Allirajah Subaskaran es el fundador de Lyca Group, una organizaci\u00f3n con filiales que operan en distintos sectores, incluidos los medios de comunicaci\u00f3n y el entretenimiento. Como presidente de Lyca Productions, Allirajah Subashkaran ha supervisado la creaci\u00f3n de varios \u00e9xitos de taquilla con un presupuesto de m\u00e1s de 50 millones de libras, produciendo historias \u00e9picas en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2312,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[123],"tags":[124,125,263,222,220],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La industria audiovisual y del entretenimiento hind\u00fa - Allirajah Subaskaran&#039;s Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/allirajahsubaskaran.com\/es\/la-industria-audiovisual-y-del-entretenimiento-hindu\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La industria audiovisual y del entretenimiento hind\u00fa - Allirajah Subaskaran&#039;s Blog\" \/>\n<meta property=\"og:description\" content=\"Allirajah Subaskaran es el fundador de Lyca Group, una organizaci\u00f3n con filiales que operan en distintos sectores, incluidos los medios de comunicaci\u00f3n y el entretenimiento. Como presidente de Lyca Productions, Allirajah Subashkaran ha supervisado la creaci\u00f3n de varios \u00e9xitos de taquilla con un presupuesto de m\u00e1s de 50 millones de libras, produciendo historias \u00e9picas en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/allirajahsubaskaran.com\/es\/la-industria-audiovisual-y-del-entretenimiento-hindu\/\" \/>\n<meta property=\"og:site_name\" content=\"Allirajah Subaskaran&#039;s Blog\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-19T10:34:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/allirajahsubaskaran.com\/wp-content\/uploads\/2023\/12\/Den-indiske-medie-og-underholdningsindustri.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/allirajahsubaskaran.com\/es\/la-industria-audiovisual-y-del-entretenimiento-hindu\/\",\"url\":\"https:\/\/allirajahsubaskaran.com\/es\/la-industria-audiovisual-y-del-entretenimiento-hindu\/\",\"name\":\"La industria audiovisual y del entretenimiento hind\u00fa - Allirajah Subaskaran&#039;s Blog\",\"isPartOf\":{\"@id\":\"https:\/\/allirajahsubaskaran.com\/es\/#website\"},\"datePublished\":\"2023-12-19T10:34:12+00:00\",\"dateModified\":\"2023-12-19T10:34:12+00:00\",\"author\":{\"@id\":\"https:\/\/allirajahsubaskaran.com\/es\/#\/schema\/person\/a04a9b0ef4f38cd38fdf5e55b8140c80\"},\"breadcrumb\":{\"@id\":\"https:\/\/allirajahsubaskaran.com\/es\/la-industria-audiovisual-y-del-entretenimiento-hindu\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/allirajahsubaskaran.com\/es\/la-industria-audiovisual-y-del-entretenimiento-hindu\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/allirajahsubaskaran.com\/es\/la-industria-audiovisual-y-del-entretenimiento-hindu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/allirajahsubaskaran.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La industria audiovisual y del entretenimiento hind\u00fa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/allirajahsubaskaran.com\/es\/#website\",\"url\":\"https:\/\/allirajahsubaskaran.com\/es\/\",\"name\":\"Allirajah Subaskaran&#039;s Blog\",\"description\":\"This is the Blog Allirajah Subaskaran&#039;s\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/allirajahsubaskaran.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/allirajahsubaskaran.com\/es\/#\/schema\/person\/a04a9b0ef4f38cd38fdf5e55b8140c80\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/allirajahsubaskaran.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b0b2742699a7e898b5fbb6d6be5bde0d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b0b2742699a7e898b5fbb6d6be5bde0d?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/allirajahsubaskaran.com\"],\"url\":\"https:\/\/allirajahsubaskaran.com\/es\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La industria audiovisual y del entretenimiento hind\u00fa - Allirajah Subaskaran&#039;s Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/allirajahsubaskaran.com\/es\/la-industria-audiovisual-y-del-entretenimiento-hindu\/","og_locale":"es_ES","og_type":"article","og_title":"La industria audiovisual y del entretenimiento hind\u00fa - Allirajah Subaskaran&#039;s Blog","og_description":"Allirajah Subaskaran es el fundador de Lyca Group, una organizaci\u00f3n con filiales que operan en distintos sectores, incluidos los medios de comunicaci\u00f3n y el entretenimiento. Como presidente de Lyca Productions, Allirajah Subashkaran ha supervisado la creaci\u00f3n de varios \u00e9xitos de taquilla con un presupuesto de m\u00e1s de 50 millones de libras, produciendo historias \u00e9picas en [&hellip;]","og_url":"https:\/\/allirajahsubaskaran.com\/es\/la-industria-audiovisual-y-del-entretenimiento-hindu\/","og_site_name":"Allirajah Subaskaran&#039;s Blog","article_published_time":"2023-12-19T10:34:12+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/allirajahsubaskaran.com\/wp-content\/uploads\/2023\/12\/Den-indiske-medie-og-underholdningsindustri.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/allirajahsubaskaran.com\/es\/la-industria-audiovisual-y-del-entretenimiento-hindu\/","url":"https:\/\/allirajahsubaskaran.com\/es\/la-industria-audiovisual-y-del-entretenimiento-hindu\/","name":"La industria audiovisual y del entretenimiento hind\u00fa - Allirajah Subaskaran&#039;s Blog","isPartOf":{"@id":"https:\/\/allirajahsubaskaran.com\/es\/#website"},"datePublished":"2023-12-19T10:34:12+00:00","dateModified":"2023-12-19T10:34:12+00:00","author":{"@id":"https:\/\/allirajahsubaskaran.com\/es\/#\/schema\/person\/a04a9b0ef4f38cd38fdf5e55b8140c80"},"breadcrumb":{"@id":"https:\/\/allirajahsubaskaran.com\/es\/la-industria-audiovisual-y-del-entretenimiento-hindu\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/allirajahsubaskaran.com\/es\/la-industria-audiovisual-y-del-entretenimiento-hindu\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/allirajahsubaskaran.com\/es\/la-industria-audiovisual-y-del-entretenimiento-hindu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/allirajahsubaskaran.com\/es\/"},{"@type":"ListItem","position":2,"name":"La industria audiovisual y del entretenimiento hind\u00fa"}]},{"@type":"WebSite","@id":"https:\/\/allirajahsubaskaran.com\/es\/#website","url":"https:\/\/allirajahsubaskaran.com\/es\/","name":"Allirajah Subaskaran&#039;s Blog","description":"This is the Blog Allirajah Subaskaran&#039;s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/allirajahsubaskaran.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/allirajahsubaskaran.com\/es\/#\/schema\/person\/a04a9b0ef4f38cd38fdf5e55b8140c80","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/allirajahsubaskaran.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b0b2742699a7e898b5fbb6d6be5bde0d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b0b2742699a7e898b5fbb6d6be5bde0d?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/allirajahsubaskaran.com"],"url":"https:\/\/allirajahsubaskaran.com\/es\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/allirajahsubaskaran.com\/es\/wp-json\/wp\/v2\/posts\/2364"}],"collection":[{"href":"https:\/\/allirajahsubaskaran.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/allirajahsubaskaran.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/allirajahsubaskaran.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/allirajahsubaskaran.com\/es\/wp-json\/wp\/v2\/comments?post=2364"}],"version-history":[{"count":0,"href":"https:\/\/allirajahsubaskaran.com\/es\/wp-json\/wp\/v2\/posts\/2364\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/allirajahsubaskaran.com\/es\/wp-json\/wp\/v2\/media\/2312"}],"wp:attachment":[{"href":"https:\/\/allirajahsubaskaran.com\/es\/wp-json\/wp\/v2\/media?parent=2364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/allirajahsubaskaran.com\/es\/wp-json\/wp\/v2\/categories?post=2364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/allirajahsubaskaran.com\/es\/wp-json\/wp\/v2\/tags?post=2364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}